{"id":11168,"date":"2026-08-31T07:59:07","date_gmt":"2026-08-31T05:59:07","guid":{"rendered":"https:\/\/moldbrothers.com\/?post_type=recipes&#038;p=11168"},"modified":"2026-08-31T07:59:07","modified_gmt":"2026-08-31T05:59:07","slug":"parmesan-tuille","status":"publish","type":"recipes","link":"https:\/\/moldbrothers.com\/de\/recipes\/parmesan-tuille\/","title":{"rendered":"Parmesan-Tuille"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Rezept reicht f\u00fcr etwa drei Parmesan-Tuille-Platten.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>150 g Mehl<\/li>\n\n\n\n<li>26 g Maisst\u00e4rke<\/li>\n\n\n\n<li>26 g Zucker<\/li>\n\n\n\n<li>8 g Salz<\/li>\n\n\n\n<li>126 g Eiwei\u00df<\/li>\n\n\n\n<li>62 g Parmesank\u00e4se<\/li>\n\n\n\n<li>126 g geschmolzene Butter<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Methode<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehl, Maisst\u00e4rke, Zucker und Salz vermischen. Eiwei\u00df, Parmesank\u00e4se und geschmolzene Butter hinzuf\u00fcgen. Mit dem Schneebesen verr\u00fchren, bis ein glatter Teig entsteht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lassen Sie den Teig \u00fcber Nacht ruhen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den Teig in die Form geben und mit einem Spachtel glatt streichen. Die Tuile bei 160 \u00b0C (320 \u00b0F) etwa 15 Minuten backen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nehmen Sie die Tuille noch warm aus der Form.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tipp: F\u00e4rben Sie einen kleinen Teil des Teigs beispielsweise mit etwas Tomatenmark ein und verteilen Sie ihn als erste Schicht in der Form, damit die Buchstaben besser zur Geltung kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":11171,"template":"","product-categorie":[18],"class_list":["post-11168","recipes","type-recipes","status-publish","has-post-thumbnail","hentry","product-categorie-2d-molds"],"_links":{"self":[{"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/recipes\/11168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/recipes"}],"about":[{"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/types\/recipes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/media\/11171"}],"wp:attachment":[{"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/media?parent=11168"}],"wp:term":[{"taxonomy":"product-categorie","embeddable":true,"href":"https:\/\/moldbrothers.com\/de\/wp-json\/wp\/v2\/product-categorie?post=11168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}