{"id":11144,"date":"2026-07-22T15:22:12","date_gmt":"2026-07-22T13:22:12","guid":{"rendered":"https:\/\/moldbrothers.com\/?post_type=recipes&#038;p=11144"},"modified":"2026-07-22T15:26:53","modified_gmt":"2026-07-22T13:26:53","slug":"pate-de-fruits-a-lolive","status":"publish","type":"recipes","link":"https:\/\/moldbrothers.com\/fr\/recipes\/olive-pate-de-fruit\/","title":{"rendered":"P\u00e2te de fruits \u00e0 l'olive"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1 bocal d'olives<\/li>\n\n\n\n<li>2 L d'eau<\/li>\n\n\n\n<li>80 g de miel<\/li>\n\n\n\n<li>1 piment<\/li>\n\n\n\n<li>40 g de gingembre frais<\/li>\n\n\n\n<li>500 g de base \u00e0 l'huile d'olive<\/li>\n\n\n\n<li>425 g de sucre<\/li>\n\n\n\n<li>60 g de sirop de glucose<\/li>\n\n\n\n<li>25 g de miel<\/li>\n\n\n\n<li>2 g d'acide citrique<\/li>\n\n\n\n<li>50 g de sucre<\/li>\n\n\n\n<li>35 g de pectine<\/li>\n\n\n\n<li>8 g d'acide citrique, dissous dans 5 g d'eau<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9thode<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Retirez du feu et incorporez imm\u00e9diatement 8 g d'acide citrique dissous dans 5 g d'eau. Versez ou \u00e9talez la p\u00e2te de fruit dans le moule tant qu'elle est encore chaude. Laissez refroidir compl\u00e8tement jusqu'\u00e0 ce qu'elle prenne, puis d\u00e9moulez d\u00e9licatement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9langez 1 bocal d'olives, 2 L d'eau, 80 g de miel, 1 piment et 40 g de gingembre frais dans une casserole. Portez \u00e0 fr\u00e9missement et laissez mijoter pendant 45 minutes. Versez le m\u00e9lange dans un mixeur \u00e0 grande vitesse et mixez jusqu'\u00e0 obtenir une texture parfaitement lisse. Passez au tamis fin si n\u00e9cessaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Versez 500 g de base d'olive dans une casserole. Ajoutez 425 g de sucre, 60 g de sirop de glucose, 25 g de miel et 2 g d'acide citrique. Faites chauffer le m\u00e9lange en remuant sans arr\u00eat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9langez 50 g de sucre avec 35 g de pectine, puis incorporez ce m\u00e9lange petit \u00e0 petit au m\u00e9lange ti\u00e8de en fouettant pour \u00e9viter la formation de grumeaux. Poursuivez la cuisson jusqu\u2019\u00e0 ce que le m\u00e9lange atteigne <strong>106 \u00b0C<\/strong>.<\/p>","protected":false},"featured_media":11147,"template":"","product-categorie":[19,23],"class_list":["post-11144","recipes","type-recipes","status-publish","has-post-thumbnail","hentry","product-categorie-3d-molds","product-categorie-testkitchen-specials"],"_links":{"self":[{"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/recipes\/11144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/recipes"}],"about":[{"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/types\/recipes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/media\/11147"}],"wp:attachment":[{"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/media?parent=11144"}],"wp:term":[{"taxonomy":"product-categorie","embeddable":true,"href":"https:\/\/moldbrothers.com\/fr\/wp-json\/wp\/v2\/product-categorie?post=11144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}