{"id":11113,"date":"2026-06-30T08:17:04","date_gmt":"2026-06-30T06:17:04","guid":{"rendered":"https:\/\/moldbrothers.com\/?post_type=recipes&#038;p=11113"},"modified":"2026-06-30T08:17:05","modified_gmt":"2026-06-30T06:17:05","slug":"il-ghiacciolo-allanguilla","status":"publish","type":"recipes","link":"https:\/\/moldbrothers.com\/it\/recipes\/the-eel-popsicle\/","title":{"rendered":"Il ghiacciolo all\u2019anguilla"},"content":{"rendered":"<h6 class=\"wp-block-heading\">Crema di anguilla<\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>100 ml di brodo di anguilla<\/li>\n\n\n\n<li>100 g di cr\u00e8me fra\u00eeche<\/li>\n\n\n\n<li>100 g di panna<\/li>\n\n\n\n<li>20 g di glucosio<\/li>\n\n\n\n<li>2 g di gelatina<\/li>\n\n\n\n<li>Succo di agrumi, q.b.<\/li>\n\n\n\n<li>Sale e pepe, a piacere<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Esterno della barbabietola rossa<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>100 g di purea di barbabietola rossa<\/li>\n\n\n\n<li>Aceto per sushi, q.b.<\/li>\n\n\n\n<li>5 g di gelatina<\/li>\n\n\n\n<li>10 g di glucosio<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Esterno del crescione<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>100 g di purea di crescione<\/li>\n\n\n\n<li>5 g di gelatina<\/li>\n\n\n\n<li>10 g di glucosio<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Ricetta per la crema di anguilla<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Sciogliere la gelatina nel brodo di anguilla.<br>Mescolare il brodo di anguilla, la cr\u00e8me fra\u00eeche, la panna, il glucosio, il succo di agrumi, il sale e il pepe fino a ottenere un composto omogeneo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Versare il composto nello stampo, inserire il bastoncino e lasciare congelare fino a quando non si sar\u00e0 completamente solidificato.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Metodo per gli esterni<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Prima di ogni utilizzo, congelare preventivamente lo stampo esterno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sciogliere la gelatina e il glucosio nella purea di barbabietola. Stendere un primo strato sottile nello stampo, eliminando l'eccesso per ottenere uno strato uniforme. Mettere in freezer fino a quando non si sar\u00e0 solidificato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ripeti la stessa procedura con la purea di crescione per il secondo strato. Rimetti in freezer finch\u00e9 non si sar\u00e0 completamente solidificato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sformare la parte esterna. Tagliare in quadrati di 5,7 x 5,7 cm. Posizionare un quadrato su un foglio di alluminio ondulato, avvolgerlo attorno alla parte interna e sigillare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Servire subito oppure conservare nel congelatore fino al momento di servire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":11116,"template":"","product-categorie":[19,23],"class_list":["post-11113","recipes","type-recipes","status-publish","has-post-thumbnail","hentry","product-categorie-3d-molds","product-categorie-testkitchen-specials"],"_links":{"self":[{"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/recipes\/11113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/recipes"}],"about":[{"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/types\/recipes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/media\/11116"}],"wp:attachment":[{"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/media?parent=11113"}],"wp:term":[{"taxonomy":"product-categorie","embeddable":true,"href":"https:\/\/moldbrothers.com\/it\/wp-json\/wp\/v2\/product-categorie?post=11113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}